{"id":2559,"date":"2026-02-10T12:15:17","date_gmt":"2026-02-10T11:15:17","guid":{"rendered":"https:\/\/lastwar-tutorial.com\/?p=2559"},"modified":"2026-02-10T12:15:18","modified_gmt":"2026-02-10T11:15:18","slug":"drohnenzentrum","status":"publish","type":"post","link":"https:\/\/lastwar-tutorial.com\/es\/drohnenzentrum\/","title":{"rendered":"Sube de nivel correctamente tu dron de Last War en el centro de drones"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2559\" class=\"elementor elementor-2559\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc5dbb9 e-flex e-con-boxed e-con e-parent\" data-id=\"fc5dbb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55a455d elementor-widget elementor-widget-text-editor\" data-id=\"55a455d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En <strong>Drone t\u00e1ctico<\/strong> es una gran palanca de poder porque proporciona efectos adicionales en batalla y apoya notablemente a tus escuadrones. Se puede utilizar en la <strong>Centro de drones<\/strong> Sube de nivel con datos de combate, piezas de drones, componentes y chips de habilidad. Con nuestros consejos podr\u00e1s subir de nivel tu dron de forma m\u00e1s r\u00e1pida y eficaz y evitar los errores t\u00edpicos.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f257d8b e-flex e-con-boxed e-con e-parent\" data-id=\"f257d8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c73764 elementor-widget elementor-widget-text-editor\" data-id=\"2c73764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>El poder de combate de tu dron depende de esto<\/h2><p>En <strong>Potencia de combate de los drones<\/strong> es un valor resumido que muestra lo fuerte que es tu dron en combate. Se compone esencialmente de tres elementos: <strong>Nivel de drones<\/strong>, <strong>Chip de capacidad<\/strong> y <strong>Componentes de drones<\/strong>.<\/p><ul><li><strong>Nivel de drones<\/strong> constituye la base: con cada nivel aumentan los valores b\u00e1sicos importantes y se puede avanzar a niveles superiores.<\/li><li>En <strong>Chip de capacidad<\/strong> aporta efectos y bonificaciones adicionales que hacen que tu dron sea notablemente m\u00e1s fuerte; a menudo, la elecci\u00f3n y mejora adecuadas son decisivas en este caso.<\/li><li><strong>Componentes de drones<\/strong> proporcionan un valor espec\u00edfico y aumentan el rendimiento a trav\u00e9s de m\u00f3dulos individuales y son ideales para aprovechar determinados puntos fuertes (por ejemplo, m\u00e1s da\u00f1os o mejor asistencia).<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d971253 elementor-widget elementor-widget-text-editor\" data-id=\"d971253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s de las tres \u00e1reas que aumentan directamente tu poder de combate con drones, tambi\u00e9n est\u00e1 el <strong>Progreso de la batalla<\/strong>. Se utiliza para <strong>Reevaluaciones<\/strong> y adem\u00e1s <strong>Habilitar ranuras de chip o funciones de chip<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdbd6b3 elementor-widget elementor-widget-text-editor\" data-id=\"cdbd6b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"text-decoration: underline;\">En resumen:<\/span><\/strong><br \/>En <strong>Nivel de su dron<\/strong> proporciona los cimientos, <strong>Fichas para efectos potentes<\/strong> y <strong>Componentes para una optimizaci\u00f3n espec\u00edfica<\/strong> - Juntos determinan la potencia de combate del dron.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9cd0cd e-flex e-con-boxed e-con e-parent\" data-id=\"e9cd0cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c203fca elementor-widget elementor-widget-text-editor\" data-id=\"c203fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Aumenta el nivel de los drones con datos de combate y piezas de drones<\/h2><p>En <strong>Nivel de drones<\/strong> es la base de la fuerza de tu dron y se determina en el centro de drones mediante <strong>Datos de combate<\/strong> y <strong>Piezas de drones<\/strong> aumentado. <strong>Datos de combate<\/strong> impulsan el aumento de nivel y son <strong>con cada actualizaci\u00f3n<\/strong> necesario. <strong>Piezas de drones<\/strong> son el material que se debe adicionalmente - especialmente en <strong>ciertos pasos de nivel<\/strong>, en funci\u00f3n del progreso.<\/p><p>En el centro de drones, puedes ver exactamente c\u00f3mo funciona cada mejora, <strong>Cu\u00e1ntos datos de combate<\/strong> y <strong>Piezas de drones<\/strong> que necesitas para el siguiente nivel. La forma m\u00e1s eficaz de subir de nivel es recopilar datos de combate con regularidad y planificar las piezas de los drones espec\u00edficamente para las siguientes fases de mejora importantes, de modo que no te atasques innecesariamente justo antes de un paso de nivel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7abee63 elementor-widget elementor-widget-text-editor\" data-id=\"7abee63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Piezas de drones y datos de combate necesarios por mejora (nivel 1-150)<\/h3><p>Para que sepas qu\u00e9 esperar, hemos creado un resumen que te indica cu\u00e1ntas piezas de dron y datos de combate necesitas para cada nivel de mejora. Hasta <strong>Nivel 150<\/strong> necesitas <strong>Partes de drones s\u00f3lo cada 5\u00ba nivel<\/strong> (5, 10, 15, ...). La cantidad aumenta por etapas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8bd319 elementor-widget elementor-widget-text-editor\" data-id=\"c8bd319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<table><thead><tr><th style=\"text-align: left;\">Nivel de drones<\/th><th>Piezas del dron (total \/ por etapa)<\/th><th>Datos de combate (total \/ por nivel)<\/th><\/tr><\/thead><tbody><tr><td>5<\/td><td>5 \/ 1<\/td><td>11.250 \/ 2.250<\/td><\/tr><tr><td>10<\/td><td>10 \/ 2<\/td><td>15.000 \/ 3.000<\/td><\/tr><tr><td>15<\/td><td>20 \/ 4<\/td><td>18.750 \/ 3.750<\/td><\/tr><tr><td>20<\/td><td>30 \/ 6<\/td><td>22.500 \/ 4.500<\/td><\/tr><tr><td>25<\/td><td>40 \/ 8<\/td><td>26.250 \/ 5.250<\/td><\/tr><tr><td>30<\/td><td>50 \/ 10<\/td><td>30.000 \/ 6.000<\/td><\/tr><tr><td>35<\/td><td>60 \/ 12<\/td><td>37.500 \/ 7.500<\/td><\/tr><tr><td>40<\/td><td>80 \/ 16<\/td><td>37.500 \/ 7.500<\/td><\/tr><tr><td>45<\/td><td>100 \/ 20<\/td><td>37.500 \/ 7.500<\/td><\/tr><tr><td>50<\/td><td>120 \/ 24<\/td><td>37.500 \/ 7.500<\/td><\/tr><tr><td>55<\/td><td>140 \/ 28<\/td><td>40.000 \/ 8.000<\/td><\/tr><tr><td>60<\/td><td>160 \/ 32<\/td><td>40.000 \/ 8.000<\/td><\/tr><tr><td>65<\/td><td>180 \/ 36<\/td><td>42.500 \/ 8.500<\/td><\/tr><tr><td>70<\/td><td>200 \/ 40<\/td><td>45.000 \/ 9.000<\/td><\/tr><tr><td>75<\/td><td>250 \/ 50<\/td><td>47.500 \/ 9.500<\/td><\/tr><tr><td>80<\/td><td>300 \/ 60<\/td><td>50.000 \/ 10.000<\/td><\/tr><tr><td>85<\/td><td>350 \/ 70<\/td><td>52.500 \/ 10.500<\/td><\/tr><tr><td>90<\/td><td>400 \/ 80<\/td><td>55.000 \/ 11.000<\/td><\/tr><tr><td>95<\/td><td>450 \/ 90<\/td><td>60.000 \/ 12.000<\/td><\/tr><tr><td>100<\/td><td>500 \/ 100<\/td><td>60.000 \/ 12.000<\/td><\/tr><tr><td>105<\/td><td>600 \/ 120<\/td><td>75.000 \/ 15.000<\/td><\/tr><tr><td>110<\/td><td>700 \/ 140<\/td><td>75.000 \/ 15.000<\/td><\/tr><tr><td>115<\/td><td>800 \/ 160<\/td><td>180.000 \/ 36.000<\/td><\/tr><tr><td>120<\/td><td>1.000 \/ 200<\/td><td>180.000 \/ 36.000<\/td><\/tr><tr><td>125<\/td><td>1.500 \/ 300<\/td><td>210.000 \/ 42.000<\/td><\/tr><tr><td>130<\/td><td>2.000 \/ 400<\/td><td>210.000 \/ 42.000<\/td><\/tr><tr><td>135<\/td><td>3.000 \/ 600<\/td><td>240.000 \/ 48.000<\/td><\/tr><tr><td>140<\/td><td>4.000 \/ 800<\/td><td>240.000 \/ 48.000<\/td><\/tr><tr><td>145<\/td><td>5.000 \/ 1.000<\/td><td>\u00a0<\/td><\/tr><tr><td>150<\/td><td>5.000 \/ 1.000<\/td><td>\u00a0<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d894cec elementor-widget elementor-widget-text-editor\" data-id=\"d894cec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>A partir del nivel 150<\/strong> se pone m\u00e1s dif\u00edcil: entonces necesitas <strong>cada nivel partes de drones<\/strong>. A partir del nivel 151, por ejemplo, son 500 por nivel y +100 cada 10 niveles (por ejemplo, de 161 \u2192 600, de 171 \u2192 700, etc.).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a36b8c7 e-con-full e-flex e-con e-child\" data-id=\"a36b8c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a469dbe e-grid e-con-full e-con e-child\" data-id=\"a469dbe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cdb90c1 e-con-full e-flex e-con e-child\" data-id=\"cdb90c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-390629e elementor-widget elementor-widget-image\" data-id=\"390629e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-2.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"drohne-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5MCwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvZHJvaG5lLTIucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"436\" height=\"772\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-2.png\" class=\"attachment-medium_large size-medium_large wp-image-2590\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-2.png 436w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-2-169x300.png 169w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-2-7x12.png 7w\" sizes=\"(max-width: 436px) 100vw, 436px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Visi\u00f3n general de los atributos y niveles del dron.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8156e4b e-con-full e-flex e-con e-child\" data-id=\"8156e4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-589051f elementor-widget elementor-widget-image\" data-id=\"589051f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-vorschau.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"drohne-vorschau\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5MiwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvZHJvaG5lLXZvcnNjaGF1LnBuZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"482\" height=\"862\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-vorschau.png\" class=\"attachment-medium_large size-medium_large wp-image-2592\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-vorschau.png 482w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-vorschau-168x300.png 168w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-vorschau-7x12.png 7w\" sizes=\"(max-width: 482px) 100vw, 482px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Previsi\u00f3n de actualizaci\u00f3n para la pr\u00f3xima gran actualizaci\u00f3n.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4da49ff e-con-full e-flex e-con e-child\" data-id=\"4da49ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb3a866 elementor-widget elementor-widget-image\" data-id=\"fb3a866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/Drohne-Skin.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Drohne-Skin\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5MywidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvRHJvaG5lLVNraW4ucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"486\" height=\"858\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/Drohne-Skin.png\" class=\"attachment-medium_large size-medium_large wp-image-2593\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/Drohne-Skin.png 486w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/Drohne-Skin-170x300.png 170w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/Drohne-Skin-7x12.png 7w\" sizes=\"(max-width: 486px) 100vw, 486px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Hay varias m\u00e1scaras (algunas de las cuales s\u00f3lo se pueden comprar) con efectos especiales para el dron.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a646b2f e-flex e-con-boxed e-con e-parent\" data-id=\"a646b2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84afbf3 elementor-widget elementor-widget-text-editor\" data-id=\"84afbf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>C\u00f3mo recopilar datos de combate y piezas de drones<\/h3><p>Los datos de combate y las piezas de drones son los dos recursos para mejorar tu dron en el centro de drones. Recoger piezas de drones suele ser especialmente tedioso y se convierte r\u00e1pidamente en un cuello de botella. Para que puedas <strong>Datos de combate<\/strong> y <strong>Piezas de drones<\/strong> y m\u00e1s r\u00e1pido, hemos elaborado un resumen de las mejores fuentes.<\/p><p><span style=\"text-decoration: underline;\"><strong>Piezas de drones:<\/strong><\/span><\/p><ul><li>Tareas diarias\u00a0<\/li><li>Alianza, Honor, Campa\u00f1a y Tienda VIP\u00a0<\/li><li>Tienda (invasi\u00f3n zombi)<\/li><li>Selecci\u00f3n de cofres de recursos<\/li><li>Operaciones fantasma (Ghost ops)<\/li><li>Mal funcionamiento del vuelo de prueba (excavaci\u00f3n)<\/li><li>Examen general<\/li><li>Vagones en el tren de la Alianza<\/li><li>Recompensas por eventos<\/li><li>Packs (paquetes de compra)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebd3f21 elementor-widget elementor-widget-text-editor\" data-id=\"ebd3f21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-decoration: underline;\"><strong>Datos de combate:<\/strong><\/span><\/p><ul><li>Misiones de radar<\/li><li>Zombis, vagabundos y la \u00e9lite de los condenados<\/li><li>Jefe zombi (Invasi\u00f3n zombi)<\/li><li>Tienda de campa\u00f1a<\/li><li>Acontecimientos especiales<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dee8ed e-flex e-con-boxed e-con e-parent\" data-id=\"0dee8ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1b06fb elementor-widget elementor-widget-text-editor\" data-id=\"b1b06fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Mejorar los componentes de los drones con m\u00f3dulos<\/h2><p>Adem\u00e1s del nivel del z\u00e1ngano, tambi\u00e9n puede controlar la fuerza de su z\u00e1ngano mediante la funci\u00f3n <strong>Componentes de drones<\/strong> aumentan. Estos son <strong>seis componentes diferentes<\/strong>, que proporcionan cada una sus propios valores y bonificaciones. La funci\u00f3n se desbloquea a partir del nivel 15 del cuartel general.<\/p><p>A trav\u00e9s de la <strong>Actualizaci\u00f3n de estos m\u00f3dulos<\/strong> su <strong>Potencia de combate de los drones<\/strong> y podr\u00e1s centrar m\u00e1s tu dron en el da\u00f1o, la supervivencia o el apoyo. Cuanto mejores y m\u00e1s avanzados sean los componentes individuales, m\u00e1s se beneficiar\u00e1n tus tropas en la batalla.<\/p><h3>Mejora de componentes hasta el nivel 7 y a partir del nivel 8<\/h3><p>Mientras su <strong>componentes equipados nivel m\u00e1ximo 7<\/strong> siempre puedes <strong>tres componentes del mismo nivel<\/strong> en un componente de nivel superior.<\/p><p>Tan pronto como el <strong>componentes equipados por primera vez Nivel 8<\/strong> la actualizaci\u00f3n funciona de forma diferente: en este caso, las mejoras se <strong>ya no fusionando<\/strong>, sino a trav\u00e9s del <strong>Valor de la investigaci\u00f3n<\/strong> del componente correspondiente. Con <strong>cada avance completo de la investigaci\u00f3n +1%<\/strong> los atributos aumentan una vez. Tambi\u00e9n hay aumentos de atributos adicionales para 20%, 40%, 60%, 80% y 100%.<\/p><p><span style=\"text-decoration: underline;\"><strong>Importante:<\/strong><\/span><br \/>Si aumentas el valor de investigaci\u00f3n en menos de 1%, no recibir\u00e1s un aumento de atributo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-813e071 e-con-full e-flex e-con e-child\" data-id=\"813e071\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fca4719 e-grid e-con-full e-con e-child\" data-id=\"fca4719\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e9a87c4 e-con-full e-flex e-con e-child\" data-id=\"e9a87c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59e7f19 elementor-widget elementor-widget-image\" data-id=\"59e7f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohnenkomponente-ueberblick.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"drohnenkomponente-\u00fcberblick\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4OSwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvZHJvaG5lbmtvbXBvbmVudGUtdWViZXJibGljay5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"486\" height=\"705\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohnenkomponente-ueberblick.png\" class=\"attachment-medium_large size-medium_large wp-image-2589\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohnenkomponente-ueberblick.png 486w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohnenkomponente-ueberblick-207x300.png 207w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohnenkomponente-ueberblick-8x12.png 8w\" sizes=\"(max-width: 486px) 100vw, 486px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Visi\u00f3n general de los componentes individuales del dron<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-572dd12 e-con-full e-flex e-con e-child\" data-id=\"572dd12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3105d elementor-widget elementor-widget-image\" data-id=\"cf3105d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-7.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"drohne-7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4NywidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvZHJvaG5lLTcucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"482\" height=\"722\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-7.png\" class=\"attachment-medium_large size-medium_large wp-image-2587\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-7.png 482w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-7-200x300.png 200w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-7-8x12.png 8w\" sizes=\"(max-width: 482px) 100vw, 482px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Hasta el nivel 7, s\u00f3lo es posible subir de nivel fusionando componentes.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f4f85f e-con-full e-flex e-con e-child\" data-id=\"5f4f85f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7107b0 elementor-widget elementor-widget-image\" data-id=\"a7107b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-8.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"drohne-8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4OCwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvZHJvaG5lLTgucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"478\" height=\"721\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-8.png\" class=\"attachment-medium_large size-medium_large wp-image-2588\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-8.png 478w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-8-199x300.png 199w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/drohne-8-8x12.png 8w\" sizes=\"(max-width: 478px) 100vw, 478px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">A partir del nivel 8, se resumen todos los componentes para el progreso.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22fa340 elementor-widget elementor-widget-text-editor\" data-id=\"22fa340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>C\u00f3mo recoger componentes de drones<\/h3><p>Por lo general, los componentes para drones se pueden adquirir en <strong>Cofres de componentes de drones<\/strong> en diferentes <strong>Niveles<\/strong>. Cuanto mayor sea el nivel del cofre, mayor ser\u00e1 el nivel de componentes que podr\u00e1s obtener de \u00e9l, por lo que merece la pena cultivar las fuentes adecuadas. Adem\u00e1s de cofres con componentes aleatorios, tambi\u00e9n hay <strong>Cofres de selecci\u00f3n de rarezas <\/strong>(Niveles 3, 4 y 5).<\/p><p><span style=\"text-decoration: underline;\"><strong>Componentes de drones:<\/strong><\/span><\/p><ul><li>Misiones secretas (nivel 2)<\/li><li>Caja de suministros misteriosa (Nivel 1)<\/li><li>Tienda de Alianzas y Campa\u00f1as (Niveles 1 y 3)<\/li><li>Taller de piezas de drones* (Nivel 1)<\/li><li>Excavaci\u00f3n - Aver\u00eda en vuelo de prueba (Nivel 1)<\/li><li>Recompensas adicionales por excavaciones (nivel 1)<\/li><li>Rango personal en el duelo diario de alianza 1-30 (nivel 4 y 3)<\/li><li>Vagones en el tren de la Alianza (Nivel 3)<\/li><li>Tienda - Invasi\u00f3n zombi (Nivel 3)<\/li><li>Taller de piezas de drones* (Nivel 1)<\/li><li>Recompensa por matar al jefe Amok (nivel\u00a0<\/li><li>Acontecimientos especiales\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793e8b0 elementor-widget elementor-widget-text-editor\" data-id=\"793e8b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>*Primera en la \u201eera del petr\u00f3leo\u201c de investigaci\u00f3n tras <a href=\"https:\/\/lastwar-tutorial.com\/es\/temporada-2\/\">Temporada 2<\/a> disponible<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21069cf e-flex e-con-boxed e-con e-parent\" data-id=\"21069cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2de7f3f elementor-widget elementor-widget-text-editor\" data-id=\"2de7f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Progreso en combate para mejorar y habilidades de fichas<\/h2><p>Adem\u00e1s del nivel del dron, el chip de habilidad y los componentes, est\u00e1 el <strong>Progreso de la batalla<\/strong> como \u00e1rea de desarrollo adicional. Trabajar\u00e1 con <strong>Tarjetas XP de progreso en combate<\/strong> y <strong>Fichas<\/strong> Progreso en una barra: si se llena, tu dron sube un nivel y se hace m\u00e1s fuerte. El punto crucial: el progreso en combate tiene <strong>Etapas especiales<\/strong>, que no s\u00f3lo mejoran los valores <strong>Otras capacidades o funciones del chip<\/strong> desbloquear.<\/p><ul><li><strong>Nivel 10<\/strong> Progreso en combate nivel 1: Desbloquea el sistema de fichas de habilidad para la primera tropa.<\/li><li><strong>Nivel 150<\/strong> Progreso de batalla nivel 2: desbloquea fichas para la segunda tropa - aumento de fichas +1<\/li><li><strong>Nivel 300<\/strong> Progreso de batalla nivel 3: desbloquea fichas para la tercera tropa - aumento de fichas +2<\/li><li><strong>Nivel 450<\/strong> Progreso de batalla nivel 4: desbloquea fichas para la cuarta tropa - aumento de fichas +3<\/li><li><strong>Nivel 600<\/strong> Progreso en combate nivel 5: Aumento de chip +4\u00a0<\/li><li><strong>Nivel 750<\/strong> Progreso en combate nivel 6: Aumento de chip +5<\/li><li><strong>Nivel 900<\/strong> Progreso de combate nivel 7: aumento masivo de atributos, aumenta el poder de combate de los drones hasta en 2,5 millones.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2340d3a e-con-full e-flex e-con e-child\" data-id=\"2340d3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0bc0946 e-grid e-con-full e-con e-child\" data-id=\"0bc0946\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1a541f0 e-con-full e-flex e-con e-child\" data-id=\"1a541f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-459ce8d elementor-widget elementor-widget-image\" data-id=\"459ce8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"kampf-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5NSwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwva2FtcGYtMS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"483\" height=\"790\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-1.png\" class=\"attachment-medium_large size-medium_large wp-image-2595\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-1.png 483w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-1-183x300.png 183w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-1-7x12.png 7w\" sizes=\"(max-width: 483px) 100vw, 483px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Resumen del nivel de progreso de la batalla<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b16ab91 e-con-full e-flex e-con e-child\" data-id=\"b16ab91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df8d972 elementor-widget elementor-widget-image\" data-id=\"df8d972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-2.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"kampf-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5NiwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwva2FtcGYtMi5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"486\" height=\"786\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-2.png\" class=\"attachment-medium_large size-medium_large wp-image-2596\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-2.png 486w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-2-185x300.png 185w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-2-7x12.png 7w\" sizes=\"(max-width: 486px) 100vw, 486px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Las tarjetas XP y otros materiales pueden a\u00f1adirse inmediatamente.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e22f991 e-con-full e-flex e-con e-child\" data-id=\"e22f991\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b51e2c9 elementor-widget elementor-widget-image\" data-id=\"b51e2c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-3.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"kampf-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU5NywidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwva2FtcGYtMy5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"491\" height=\"747\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-3.png\" class=\"attachment-medium_large size-medium_large wp-image-2597\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-3.png 491w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-3-197x300.png 197w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/kampf-3-8x12.png 8w\" sizes=\"(max-width: 491px) 100vw, 491px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Adem\u00e1s de la selecci\u00f3n r\u00e1pida, tambi\u00e9n se pueden a\u00f1adir materiales individuales espec\u00edficamente <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c48ba elementor-widget elementor-widget-text-editor\" data-id=\"a3c48ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>C\u00f3mo recoger tarjetas de XP de progreso de batalla<\/h3><p><strong>Fichas y tarjetas de XP por progreso en batalla<\/strong> se obtiene sobre todo de <strong>peri\u00f3dico semanal<\/strong> Fuentes. Las fichas suelen proceder de tiendas (tiendas VIP, de alianzas y de honor), cofres de recompensa y eventos (invasi\u00f3n zombi o misiones fantasma). <strong>Tarjetas XP<\/strong> suelen proceder de las mismas fuentes y adem\u00e1s a menudo de <strong>Contenido PvE <\/strong>(examen del general) y <strong>Recompensas por hitos<\/strong>, porque aumentan directamente la barra de progreso del dron.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c158d35 e-flex e-con-boxed e-con e-parent\" data-id=\"c158d35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb0ca68 elementor-widget elementor-widget-text-editor\" data-id=\"eb0ca68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Mejora el dron t\u00e1ctico con fichas de habilidad<\/h2><p>Con los chips de habilidad, puedes dar a tu dron\u00a0<strong>Efectos y bonificaciones adicionales<\/strong> dar. En total hay <strong>Hasta cuatro juegos de fichas de tropa<\/strong>, recomendamos <strong>Al menos un juego de fichas por tipo de tropa <\/strong>de usar. Los conjuntos de fichas individuales se desbloquean paso a paso a medida que avanza la batalla.<\/p><p>Puede <strong>Equipar y mejorar las fichas de habilidad<\/strong>, para aumentar su efecto. Lo importante aqu\u00ed no es s\u00f3lo la fuerza de un chip individual, sino tambi\u00e9n la <strong>Combinaci\u00f3n sensata<\/strong> de las fichas con la tropa correspondiente para que los efectos encajen bien.<\/p><p>Le recomendamos que cree un juego de fichas adecuado para cada tropa:<\/p><ul><li>Fichas de blindaje (principalmente 1\u00aa tropa)<\/li><li>Juego de fichas de avi\u00f3n (la mayor\u00eda de 2\u00aa tropa)<\/li><li>Fichas de veh\u00edculos cohete (normalmente 3\u00aa tropa)<\/li><li>Mezcla de patatas fritas (4\u00aa tropa)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f51030 e-con-full e-flex e-con e-child\" data-id=\"6f51030\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-90783ea e-grid e-con-full e-con e-child\" data-id=\"90783ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9851b57 e-con-full e-flex e-con e-child\" data-id=\"9851b57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8347f7e elementor-widget elementor-widget-image\" data-id=\"8347f7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"set-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4NCwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvc2V0LTEucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"482\" height=\"545\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-1.png\" class=\"attachment-medium_large size-medium_large wp-image-2584\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-1.png 482w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-1-265x300.png 265w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-1-11x12.png 11w\" sizes=\"(max-width: 482px) 100vw, 482px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un juego de fichas para tanques.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27dc3a8 e-con-full e-flex e-con e-child\" data-id=\"27dc3a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75b5d78 elementor-widget elementor-widget-image\" data-id=\"75b5d78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-2.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"set-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4NSwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvc2V0LTIucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"485\" height=\"543\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-2.png\" class=\"attachment-medium_large size-medium_large wp-image-2585\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-2.png 485w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-2-268x300.png 268w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-2-11x12.png 11w\" sizes=\"(max-width: 485px) 100vw, 485px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un chipset para aviones.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13137ad e-con-full e-flex e-con e-child\" data-id=\"13137ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75fd8f6 elementor-widget elementor-widget-image\" data-id=\"75fd8f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-3.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"set-3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjU4NiwidXJsIjoiaHR0cHM6XC9cL2xhc3R3YXItdHV0b3JpYWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI2XC8wMlwvc2V0LTMucG5nIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"487\" height=\"546\" src=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-3.png\" class=\"attachment-medium_large size-medium_large wp-image-2586\" alt=\"\" srcset=\"https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-3.png 487w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-3-268x300.png 268w, https:\/\/lastwar-tutorial.com\/wp-content\/uploads\/2026\/02\/set-3-11x12.png 11w\" sizes=\"(max-width: 487px) 100vw, 487px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un juego de chips para veh\u00edculos cohete.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3696457 elementor-widget elementor-widget-text-editor\" data-id=\"3696457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Mejora y producci\u00f3n de chips<\/h3><p>Con <strong>Fichas SSR y UR<\/strong> tienes dos niveles de rareza a tu disposici\u00f3n. Para hacerte m\u00e1s fuerte lo antes posible, debes <strong>Recoge las mismas fichas<\/strong> y su <strong>Actualizar el chipset inmediatamente<\/strong>. Un cambio de <strong>SSR en UR<\/strong> s\u00f3lo merece la pena si el chip UR <strong>realmente m\u00e1s poder de combate<\/strong> que tu chip SSR actual.<\/p><p>La forma m\u00e1s r\u00e1pida de progresar es utilizar la funci\u00f3n <a href=\"https:\/\/lastwar-tutorial.com\/es\/laboratorio-de-chips\/\">laboratorio de chips con material de chips para producir chips espec\u00edficos<\/a> y adem\u00e1s tantos <strong>Arquetas<\/strong> como sea posible.<\/p><p><span style=\"text-decoration: underline;\"><strong>As\u00ed se consiguen los cofres de fichas:<\/strong><\/span><\/p><ul><li>Competencia profesional \u201eoferta de drones\u201c<\/li><li>Alianza, Honor, Campa\u00f1a y Tienda VIP\u00a0<\/li><li>Recompensa por ghosting<\/li><li>Recompensas de eventos (Tormenta del Ca\u00f1\u00f3n)<\/li><li>Packs (paquetes de compra)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-baa289d e-flex e-con-boxed e-con e-parent\" data-id=\"baa289d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47b9fa9 elementor-widget elementor-widget-text-editor\" data-id=\"47b9fa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Trucos y consejos para subir de nivel el dron t\u00e1ctico\u00a0<\/h2><p>Para fortalecer tu dron de la forma m\u00e1s eficaz posible, aqu\u00ed encontrar\u00e1s consejos pr\u00e1cticos para la nivelaci\u00f3n:<\/p><ul><li><strong>Recoger las piezas del dron lo antes posible<\/strong>, aunque no los necesites ahora: casi siempre se convierten en un cuello de botella m\u00e1s adelante.<\/li><li>Adquirir semanalmente <strong>todas las piezas de drones disponibles<\/strong> en el <strong>Tienda Allianz y Tienda Campa\u00f1a<\/strong>, si sus recursos se lo permiten.<\/li><li><strong> Nivele su dron el lunes<\/strong> con<strong> Datos de combate y piezas de drones<\/strong>, para ganar puntos adicionales en el duelo VS.<\/li><li><strong>Abrir los cofres de fichas de habilidad el lunes<\/strong>, para que pueda <strong>Puntos VS<\/strong> conseguir.<\/li><li><strong>Abrir los cofres de componentes de drones el mi\u00e9rcoles<\/strong>, para asegurar los puntos VS correspondientes.<\/li><li><strong>Utilizar el laboratorio de chips<\/strong>, para <strong>producir las fichas de habilidad que faltan<\/strong>, en lugar de limitarse a esperar la casualidad.<\/li><li><strong>Re\u00fane fichas id\u00e9nticas estrat\u00e9gicamente<\/strong> y utiliza las fichas que no necesites para el <strong>Progreso de la batalla<\/strong> tu dron.<\/li><li>Establecer <strong>Cofres de selecci\u00f3n para componentes de drones<\/strong> para obtener exactamente el componente que necesita para la siguiente L<strong>evel\/upgrade step<\/strong> desaparecida.<\/li><li>Uso para <strong>Cada tropa recibe chips de capacidad estandarizados<\/strong> (tanques, aviones y veh\u00edculos de misiles).<\/li><li>Sustituir lo antes posible <strong>Chips SSR a trav\u00e9s de chips de capacidad UR<\/strong>, si su aumento de poder de combate es mayor.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die taktische Drohne ist ein gro\u00dfer Power-Hebel, weil sie im Kampf zus\u00e4tzliche Effekte liefert und deine Trupps sp\u00fcrbar unterst\u00fctzt. Diese l\u00e4sst sich im Drohnenzentrum mit Kampfdaten, Drohnenteilen, Komponenten, F\u00e4higkeitschips leveln. Mit unseren Tipps kannst du deine Drohne effekiver und schneller upgraden und vermeidest typische Fehler.\u00a0 Davon h\u00e4ngt die Kampfkraft deiner Drohne ab Die Drohnenkampfkraft ist [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/posts\/2559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/comments?post=2559"}],"version-history":[{"count":21,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/posts\/2559\/revisions"}],"predecessor-version":[{"id":2628,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/posts\/2559\/revisions\/2628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/media\/2604"}],"wp:attachment":[{"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/media?parent=2559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/categories?post=2559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lastwar-tutorial.com\/es\/wp-json\/wp\/v2\/tags?post=2559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}